{"id":403,"date":"2022-03-23T20:08:05","date_gmt":"2022-03-23T19:08:05","guid":{"rendered":"https:\/\/anwalt-alicante.com\/descargo-de-responsabilidad\/"},"modified":"2022-03-29T14:14:26","modified_gmt":"2022-03-29T12:14:26","slug":"descargo-de-responsabilidad","status":"publish","type":"page","link":"https:\/\/anwalt-alicante.com\/es\/descargo-de-responsabilidad\/","title":{"rendered":"Descargo de responsabilidad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"403\" class=\"elementor elementor-403\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-260f96b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"260f96b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ea27c8\" data-id=\"7ea27c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99227a5 elementor-widget elementor-widget-text-editor\" data-id=\"99227a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Descargo de responsabilidad<\/h2>\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document disclaimer cmplz-document-all\"><p>DR. FR\u00dcHBECK ABOGADOS se compromete a mantener esta web actualizada y precisa. Si, a pesar de todo, encontrara algo incorrecto o desactualizado, le agradecer\u00edamos que nos lo hiciera saber. Por favor, indique en qu\u00e9 parte de la web ha le\u00eddo la informaci\u00f3n. La revisaremos lo antes posible. Por favor, env\u00ede su duda por correo electr\u00f3nico a: <span class=\"cmplz-obfuscate\">&#105;&#110;f&#111;@<span class=\"cmplz-fmail-domain\">&#101;&#120;.com<\/span>&#102;&#114;&#117;&#104;&#098;ec&#107;&#046;&#099;&#111;&#109;<\/span>.<\/p><p>No nos responsabilizamos de las p\u00e9rdidas derivadas de inexactitudes o datos incompletos, ni de las p\u00e9rdidas resultantes de problemas causados o inherentes a la difusi\u00f3n de la informaci\u00f3n a trav\u00e9s de Internet, como interrupciones o fallos. Al utilizar formularios web, nos esforzamos por limitar al m\u00ednimo el n\u00famero de campos obligatorios. Por cualquier p\u00e9rdida sufrida como resultado del uso de datos, consejos o ideas proporcionadas por DR. FR\u00dcHBECK ABOGADOS o en su nombre a trav\u00e9s de esta web, DR. FR\u00dcHBECK ABOGADOS no acepta ninguna responsabilidad.<\/p><p>Las respuestas y preguntas sobre privacidad enviadas por correo electr\u00f3nico o a trav\u00e9s de un formulario web ser\u00e1n tratadas de la misma manera que las cartas. Esto significa que puede esperar una respuesta nuestra en un plazo m\u00e1ximo de 1 mes. En el caso de solicitudes complejas, le informaremos en el plazo de 1 mes si necesitamos un m\u00e1ximo de 3 meses.<\/p><p>Cualquier dato personal que nos proporcione en el contexto de su respuesta o solicitud de informaci\u00f3n s\u00f3lo se utilizar\u00e1 de acuerdo con nuestra declaraci\u00f3n de privacidad.<\/p><p>DR. FR\u00dcHBECK ABOGADOS har\u00e1 todos los esfuerzos razonables para proteger sus sistemas contra cualquier forma de uso il\u00edcito. DR. FR\u00dcHBECK ABOGADOS aplicar\u00e1 las medidas t\u00e9cnicas y organizativas adecuadas a tal fin, teniendo en cuenta, entre otras cosas, el estado de la t\u00e9cnica. No obstante, no ser\u00e1 responsable de ning\u00fan perjuicio, directo y\/o indirecto, sufrido por un usuario de la web, que se derive del uso il\u00edcito de sus sistemas por parte de un tercero.<\/p><p>DR. FR\u00dcHBECK ABOGADOS no se hace responsable del contenido de las p\u00e1ginas web a las que se hace referencia mediante hiperv\u00ednculos u otras referencias. Los productos o servicios ofrecidos por terceros estar\u00e1n sujetos a los t\u00e9rminos y condiciones aplicables de dichos terceros.<\/p><p>Todos los derechos de propiedad intelectual sobre el contenido de esta web pertenecen a DR. FR\u00dcHBECK ABOGADOS.<\/p><p>La copia, difusi\u00f3n y cualquier otro uso de estos materiales no est\u00e1 permitido sin el permiso escrito de DR. FR\u00dcHBECK ABOGADOS, excepto y s\u00f3lo en la medida en que se estipule lo contrario en los reglamentos de la ley obligatoria (como el derecho de cita), a menos que el contenido espec\u00edfico dicte lo contrario.<\/p><p>Si tiene alguna pregunta o problema con la accesibilidad de la web, no dude en ponerse en contacto con nosotros.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Descargo de responsabilidad<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-403","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/pages\/403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/comments?post=403"}],"version-history":[{"count":10,"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/pages\/403\/revisions"}],"predecessor-version":[{"id":803,"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/pages\/403\/revisions\/803"}],"wp:attachment":[{"href":"https:\/\/anwalt-alicante.com\/es\/wp-json\/wp\/v2\/media?parent=403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}